ส่งสินค้าไปอเมริกา โดยทีมงานมืออาชีพ ทางเลือกที่ดีที่สุดของคุณสำหรับการขนส่งและโลจิสติกส์ ส่งสินค้าไปอเมริกา บริษัท ควอลิตี้เฟรทอินเตอร์เนชั่นแนล จำกัด ก่อตั้งขึ้นในปี 2542 ในกรุงเทพฯโดยกลุ่มผู้บริหารที่มีประสบการณ์ในด้านธุรกิจขนส่งสินค้าและเป็นผู้ที่มีประสบการณ์อื่น...<div class='mt-2 taglist'>{"id":2162,"date":"2022-02-05T10:52:30","date_gmt":"2022-02-05T03:52:30","guid":{"rendered":"https:\/\/qualityaccessgloballogistics.com\/?p=2162"},"modified":"2024-08-22T22:28:52","modified_gmt":"2024-08-22T15:28:52","slug":"%e0%b8%aa%e0%b9%88%e0%b8%87%e0%b8%aa%e0%b8%b4%e0%b8%99%e0%b8%84%e0%b9%89%e0%b8%b2%e0%b9%84%e0%b8%9b%e0%b8%ad%e0%b9%80%e0%b8%a1%e0%b8%a3%e0%b8%b4%e0%b8%81%e0%b8%b2-%e0%b8%aa%e0%b8%ad%e0%b8%9a%e0%b8%96","status":"publish","type":"post","link":"https:\/\/qualityaccessgloballogistics.com\/th\/%e0%b8%aa%e0%b9%88%e0%b8%87%e0%b8%aa%e0%b8%b4%e0%b8%99%e0%b8%84%e0%b9%89%e0%b8%b2%e0%b9%84%e0%b8%9b%e0%b8%ad%e0%b9%80%e0%b8%a1%e0%b8%a3%e0%b8%b4%e0%b8%81%e0%b8%b2-%e0%b8%aa%e0%b8%ad%e0%b8%9a%e0%b8%96\/","title":{"rendered":"\u0e2a\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e44\u0e1b\u0e2d\u0e40\u0e21\u0e23\u0e34\u0e01\u0e32 \u0e2a\u0e2d\u0e1a\u0e16\u0e32\u0e21\u0e04\u0e48\u0e32\u0e2a\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e23\u0e32\u0e04\u0e32\u0e42\u0e1b\u0e42\u0e21\u0e0a\u0e31\u0e48\u0e19"},"content":{"rendered":"<p><span style=\"color: #0000ff;\">\u0e2a\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e44\u0e1b\u0e2d\u0e40\u0e21\u0e23\u0e34\u0e01\u0e32 <\/span>\u0e42\u0e14\u0e22\u0e17\u0e35\u0e21\u0e07\u0e32\u0e19\u0e21\u0e37\u0e2d\u0e2d\u0e32\u0e0a\u0e35\u0e1e \u0e17\u0e32\u0e07\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e17\u0e35\u0e48\u0e14\u0e35\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14\u0e02\u0e2d\u0e07\u0e04\u0e38\u0e13\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c<\/p>\n<div class=\"elementor-element elementor-element-9ab42ee elementor-widget elementor-widget-heading\" data-id=\"9ab42ee\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n<div class=\"elementor-widget-container\">\n<h4 class=\"elementor-heading-title elementor-size-default\" style=\"text-align: center;\"><span style=\"color: #0000ff;\"><strong>\u0e2a\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e44\u0e1b\u0e2d\u0e40\u0e21\u0e23\u0e34\u0e01\u0e32<\/strong><\/span><a href=\"https:\/\/qualityaccessgloballogistics.com\/th\/\"><img decoding=\"async\" class=\"aligncenter wp-image-1485 size-medium\" src=\"https:\/\/qualityaccessgloballogistics.com\/wp-content\/uploads\/2022\/01\/bg10-300x164.jpg\" alt=\"\u0e2a\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e44\u0e1b\u0e2d\u0e40\u0e21\u0e23\u0e34\u0e01\u0e32\" width=\"300\" height=\"164\" title=\"- Quality Freight International\" srcset=\"https:\/\/qualityaccessgloballogistics.com\/wp-content\/uploads\/2022\/01\/bg10-300x164.jpg 300w, https:\/\/qualityaccessgloballogistics.com\/wp-content\/uploads\/2022\/01\/bg10-1024x559.jpg 1024w, https:\/\/qualityaccessgloballogistics.com\/wp-content\/uploads\/2022\/01\/bg10-768x419.jpg 768w, https:\/\/qualityaccessgloballogistics.com\/wp-content\/uploads\/2022\/01\/bg10-1536x838.jpg 1536w, https:\/\/qualityaccessgloballogistics.com\/wp-content\/uploads\/2022\/01\/bg10-18x10.jpg 18w, https:\/\/qualityaccessgloballogistics.com\/wp-content\/uploads\/2022\/01\/bg10.jpg 1980w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/h4>\n<\/div>\n<\/div>\n<div class=\"elementor-element elementor-element-08ee244 elementor-widget elementor-widget-text-editor\" data-id=\"08ee244\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n<div class=\"elementor-widget-container\">\n<p>\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e04\u0e27\u0e2d\u0e25\u0e34\u0e15\u0e35\u0e49\u0e40\u0e1f\u0e23\u0e17\u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e0a\u0e31\u0e48\u0e19\u0e41\u0e19\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 \u0e01\u0e48\u0e2d\u0e15\u0e31\u0e49\u0e07\u0e02\u0e36\u0e49\u0e19\u0e43\u0e19\u0e1b\u0e35 2542 \u0e43\u0e19\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e2f\u0e42\u0e14\u0e22\u0e01\u0e25\u0e38\u0e48\u0e21\u0e1c\u0e39\u0e49\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e17\u0e35\u0e48\u0e21\u0e35\u0e1b\u0e23\u0e30\u0e2a\u0e1a\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e43\u0e19\u0e14\u0e49\u0e32\u0e19\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e41\u0e25\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e1c\u0e39\u0e49\u0e17\u0e35\u0e48\u0e21\u0e35\u0e1b\u0e23\u0e30\u0e2a\u0e1a\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e2d\u0e37\u0e48\u0e19 \u0e46<\/p>\n<\/div>\n<\/div>\n<div class=\"elementor-element elementor-element-100bdff elementor-widget elementor-widget-text-editor\" data-id=\"100bdff\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n<div class=\"elementor-widget-container\">\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e0b\u0e36\u0e48\u0e07\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e43\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07 \/ \u0e01\u0e32\u0e23\u0e2a\u0e48\u0e07\u0e21\u0e2d\u0e1a\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e21\u0e32\u0e01\u0e27\u0e48\u0e32 22 \u0e1b\u0e35\u0e14\u0e49\u0e27\u0e22\u0e04\u0e27\u0e32\u0e21\u0e21\u0e38\u0e48\u0e07\u0e21\u0e31\u0e48\u0e19\u0e17\u0e35\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e40\u0e19\u0e49\u0e19\u0e43\u0e2b\u0e49\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e1e\u0e36\u0e07\u0e1e\u0e2d\u0e43\u0e08\u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2a\u0e39\u0e07\u0e2a\u0e38\u0e14<\/div>\n<\/div>\n<div>\n<div class=\"elementor-element elementor-element-9ea66d9 elementor-widget elementor-widget-text-editor\" data-id=\"9ea66d9\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n<div class=\"elementor-widget-container\">\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/www.google.com\/search?q=Quality+Freight+International\" target=\"_blank\" rel=\"noopener\"><strong><span style=\"text-decoration: underline;\">\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e04\u0e27\u0e2d\u0e25\u0e34\u0e15\u0e35\u0e49 \u0e41\u0e2d\u0e04\u0e40\u0e0b\u0e2a \u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 \u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14<\/span><\/strong><\/a>\u00a0\u0e40\u0e1b\u0e47\u0e19\u0e1c\u0e39\u0e49\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e17\u0e35\u0e48\u0e2b\u0e25\u0e32\u0e01\u0e2b\u0e25\u0e32\u0e22\u0e43\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e19\u0e35\u0e49 \u0e42\u0e14\u0e22\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2b\u0e25\u0e31\u0e01\u0e41\u0e25\u0e30\u0e02\u0e2d\u0e1a\u0e40\u0e02\u0e15\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e02\u0e2d\u0e07\u0e40\u0e23\u0e32\u0e04\u0e23\u0e2d\u0e1a\u0e04\u0e25\u0e38\u0e21\u0e14\u0e31\u0e07\u0e15\u0e48\u0e2d\u0e44\u0e1b\u0e19\u0e35\u0e49<\/p>\n<ul>\n<li>\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22\u0e14\u0e49\u0e32\u0e19\u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e01\u0e31\u0e1a\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e17\u0e31\u0e48\u0e27\u0e42\u0e25\u0e01<\/li>\n<li>\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e17\u0e32\u0e07\u0e17\u0e30\u0e40\u0e25 (LCL &amp; FCL)<\/li>\n<li>\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e32\u0e01\u0e32\u0e28 (\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e40\u0e19\u0e48\u0e32\u0e40\u0e2a\u0e35\u0e22\u0e07\u0e48\u0e32\u0e22 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e31\u0e19\u0e15\u0e23\u0e32\u0e22)<\/li>\n<li>\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 LCL Consolidation : \u0e42\u0e14\u0e22\u0e15\u0e39\u0e49\u0e02\u0e2d\u0e07\u0e40\u0e23\u0e32\u0e04\u0e23\u0e2d\u0e1a\u0e04\u0e25\u0e38\u0e21\u0e17\u0e48\u0e32\u0e40\u0e23\u0e37\u0e2d\u0e2b\u0e25\u0e31\u0e01\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e21\u0e14<\/li>\n<li>\u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32\u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23 (\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01) \u0e40\u0e14\u0e34\u0e19\u0e1e\u0e34\u0e18\u0e35\u0e01\u0e32\u0e23\u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23\u0e42\u0e14\u0e22\u0e1c\u0e39\u0e49\u0e40\u0e0a\u0e35\u0e48\u0e22\u0e27\u0e0a\u0e32\u0e0d<\/li>\n<li>\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e2b\u0e25\u0e32\u0e01\u0e2b\u0e25\u0e32\u0e22\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a\u0e20\u0e32\u0e22\u0e43\u0e15\u0e49\u0e40\u0e07\u0e37\u0e48\u0e2d\u0e19\u0e44\u0e02\u0e15\u0e48\u0e32\u0e07\u0e46<\/li>\n<li>\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e17\u0e32\u0e07\u0e1a\u0e01 \u0e41\u0e25\u0e30\u0e02\u0e19\u0e1c\u0e48\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22\u0e44\u0e1b\u0e22\u0e31\u0e07\u0e17\u0e35\u0e48\u0e15\u0e48\u0e32\u0e07\u0e46<\/li>\n<li>\u0e04\u0e48\u0e32\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e17\u0e32\u0e07\u0e1a\u0e01 (\u0e1a\u0e23\u0e23\u0e17\u0e38\u0e01\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e40\u0e15\u0e47\u0e21\u0e15\u0e39\u0e49\u0e04\u0e2d\u0e19\u0e40\u0e17\u0e19\u0e40\u0e19\u0e2d\u0e23\u0e4c\u0e41\u0e25\u0e30\u0e1a\u0e23\u0e23\u0e17\u0e38\u0e01\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e1a\u0e32\u0e07\u0e2a\u0e48\u0e27\u0e19)<\/li>\n<li>\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e02\u0e49\u0e32\u0e21\u0e41\u0e14\u0e19 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e19\u0e1a\u0e49\u0e32\u0e19)<\/li>\n<li>\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e31\u0e19\u0e15\u0e23\u0e32\u0e22<\/li>\n<li>\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e15\u0e39\u0e49\u0e04\u0e2d\u0e19\u0e40\u0e17\u0e19\u0e40\u0e19\u0e2d\u0e23\u0e4c\u0e1e\u0e34\u0e40\u0e28\u0e29 (\u0e15\u0e39\u0e49\u0e40\u0e1b\u0e34\u0e14\u0e14\u0e49\u0e32\u0e19\u0e1a\u0e19 \u0e15\u0e39\u0e49\u0e40\u0e1b\u0e34\u0e14\u0e02\u0e49\u0e32\u0e07 \u0e2f\u0e25\u0e2f)<\/li>\n<li>\u0e40\u0e23\u0e37\u0e2d\u0e40\u0e17\u0e01\u0e2d\u0e07 \u0e40\u0e0a\u0e48\u0e19 \u0e19\u0e49\u0e33\u0e15\u0e32\u0e25 \u0e02\u0e49\u0e32\u0e27 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23\u0e02\u0e19\u0e32\u0e14\u0e43\u0e2b\u0e0d\u0e48 \u0e2f\u0e25\u0e2f<\/li>\n<li>\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\u0e40\u0e04\u0e25\u0e35\u0e22\u0e23\u0e4c\u0e1e\u0e31\u0e2a\u0e14\u0e38<\/li>\n<li>\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2a\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e16\u0e36\u0e07\u0e2b\u0e19\u0e49\u0e32\u0e1a\u0e49\u0e32\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e2b\u0e19\u0e49\u0e32\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19 (DDU, DDP, DAP, \u0e2f\u0e25\u0e2f )<\/li>\n<\/ul>\n<p><strong>\u0e2a\u0e2d\u0e1a\u0e16\u0e32\u0e21\u0e2d\u0e31\u0e15\u0e32\u0e04\u0e48\u0e32\u0e2a\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e44\u0e1b\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e17\u0e32\u0e07\u0e40\u0e23\u0e37\u0e2d \u0e17\u0e32\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e34\u0e19<\/strong><strong>\u00a0<\/strong><\/p>\n<p>LINE :\u00a0<a href=\"https:\/\/page.line.me\/963fyukk?openQrModal=true\" target=\"_blank\" rel=\"noopener\">https:\/\/page.line.me\/963fyukk?openQrModal=true<\/a><\/p>\n<p>WEB:\u00a0<a href=\"https:\/\/qualityaccessgloballogistics.com\/th\/\">https:\/\/qualityaccessgloballogistics.com<\/a><\/p>\n<p>TEL:\u00a0\u00a002 714 3011<\/p>\n<\/div>\n<\/div>\n<div class=\"elementor-element elementor-element-c9e1586 elementor-widget elementor-widget-text-editor\" data-id=\"c9e1586\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n<div class=\"elementor-widget-container\">\n<p><strong>The Licensed Customs Broker:<\/strong> \u0e40\u0e23\u0e32\u0e21\u0e35\u0e17\u0e35\u0e21\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e40\u0e0a\u0e35\u0e48\u0e22\u0e27\u0e0a\u0e32\u0e0d\u0e43\u0e19\u0e17\u0e38\u0e01\u0e02\u0e31\u0e49\u0e19\u0e15\u0e2d\u0e19\u0e02\u0e2d\u0e07\u0e1e\u0e34\u0e18\u0e35\u0e01\u0e32\u0e23\u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e04\u0e38\u0e13\u0e08\u0e30\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e14\u0e35\u0e08\u0e32\u0e01\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e1c\u0e48\u0e32\u0e19\u0e01\u0e32\u0e23\u0e1d\u0e36\u0e01\u0e2d\u0e1a\u0e23\u0e21\u0e21\u0e32\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e14\u0e35\u0e02\u0e2d\u0e07\u0e40\u0e23\u0e32\u0e0b\u0e36\u0e48\u0e07\u0e21\u0e35\u0e1b\u0e23\u0e30\u0e2a\u0e1a\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e43\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e19\u0e35\u0e49\u0e21\u0e32\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e22\u0e32\u0e27\u0e19\u0e32\u0e19\u0e41\u0e25\u0e30\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e43\u0e19\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e21\u0e14<\/p>\n<\/div>\n<\/div>\n<p>&nbsp;<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"wp-image-1970 size-large\" src=\"https:\/\/qualityaccessgloballogistics.com\/wp-content\/uploads\/2022\/01\/Quality-Freight-International-1024x678.jpg\" alt=\"Quality Freight International\" width=\"1024\" height=\"678\" title=\"- Quality Freight International\" srcset=\"https:\/\/qualityaccessgloballogistics.com\/wp-content\/uploads\/2022\/01\/Quality-Freight-International-1024x678.jpg 1024w, https:\/\/qualityaccessgloballogistics.com\/wp-content\/uploads\/2022\/01\/Quality-Freight-International-300x199.jpg 300w, https:\/\/qualityaccessgloballogistics.com\/wp-content\/uploads\/2022\/01\/Quality-Freight-International-768x508.jpg 768w, https:\/\/qualityaccessgloballogistics.com\/wp-content\/uploads\/2022\/01\/Quality-Freight-International-18x12.jpg 18w, https:\/\/qualityaccessgloballogistics.com\/wp-content\/uploads\/2022\/01\/Quality-Freight-International.jpg 1360w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<div class=\"elementor-element elementor-element-c9e1586 elementor-widget elementor-widget-text-editor\" data-id=\"c9e1586\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n<div class=\"elementor-widget-container\">\n<div class=\"elementor-element elementor-element-e206d8e elementor-widget elementor-widget-text-editor\" data-id=\"e206d8e\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n<div class=\"elementor-widget-container\">\n<p><strong>\u0e42\u0e14\u0e22\u0e40\u0e23\u0e32\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e40\u0e0a\u0e35\u0e48\u0e22\u0e27\u0e0a\u0e32\u0e0d\u0e43\u0e19\u0e23\u0e32\u0e22\u0e25\u0e30\u0e40\u0e2d\u0e35\u0e22\u0e14\u0e07\u0e32\u0e19\u0e14\u0e31\u0e07\u0e15\u0e48\u0e2d\u0e44\u0e1b\u0e19\u0e35\u0e49<\/strong><\/p>\n<\/div>\n<\/div>\n<div class=\"elementor-element elementor-element-60bce86 elementor-widget elementor-widget-text-editor\" data-id=\"60bce86\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n<div class=\"elementor-widget-container\">\n<ul>\n<li>\u0e1e\u0e34\u0e18\u0e35\u0e01\u0e32\u0e23\u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01\u0e41\u0e25\u0e30\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32<\/li>\n<li>\u0e23\u0e30\u0e40\u0e1a\u0e35\u0e22\u0e1a BOI<\/li>\n<li>\u0e1e\u0e34\u0e18\u0e35\u0e01\u0e32\u0e23 BIS 19<\/li>\n<li>\u0e02\u0e2d\u0e04\u0e37\u0e19\u0e21\u0e38\u0e21\u0e2a\u0e35\u0e19\u0e49\u0e33\u0e40\u0e07\u0e34\u0e19<\/li>\n<li>\u0e1e\u0e34\u0e18\u0e35\u0e01\u0e32\u0e23\u0e04\u0e25\u0e31\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e31\u0e13\u0e11\u0e4c\u0e1a\u0e19<\/li>\n<li>\u0e1e\u0e34\u0e18\u0e35\u0e01\u0e32\u0e23 EPZ \u0e41\u0e25\u0e30 \u0e42\u0e0b\u0e19\u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e22\u0e01\u0e40\u0e27\u0e49\u0e19\u0e20\u0e32\u0e29\u0e35<\/li>\n<li>\u0e1e\u0e34\u0e18\u0e35\u0e01\u0e32\u0e23\u0e02\u0e49\u0e32\u0e21\u0e1e\u0e23\u0e21\u0e41\u0e14\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e19\u0e1a\u0e49\u0e32\u0e19<\/li>\n<li>\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01\u0e41\u0e25\u0e30\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32<\/li>\n<li>\u0e17\u0e33\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e20\u0e31\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32<\/li>\n<\/ul>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div><strong>\u0e2a\u0e2d\u0e1a\u0e16\u0e32\u0e21\u0e2d\u0e31\u0e15\u0e32\u0e04\u0e48\u0e32\u0e2a\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e44\u0e1b\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e17\u0e32\u0e07\u0e40\u0e23\u0e37\u0e2d \u0e17\u0e32\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e34\u0e19\u00a0<\/strong><\/div>\n<div><span style=\"font-family: var(--global-body-font-family);\">LINE : <\/span><a style=\"font-family: var(--global-body-font-family);\" href=\"https:\/\/page.line.me\/963fyukk?openQrModal=true\" target=\"_blank\" rel=\"noopener\">https:\/\/page.line.me\/963fyukk?openQrModal=true<\/a><\/div>\n<div>WEB: <a href=\"https:\/\/qualityaccessgloballogistics.com\/th\/\">https:\/\/qualityaccessgloballogistics.com<\/a><\/div>\n<div>TEL: <span style=\"font-family: var(--global-body-font-family);\">\u00a002 714 3011<\/span><\/div>","protected":false},"excerpt":{"rendered":"<a href=\"https:\/\/qualityaccessgloballogistics.com\/th\/tag\/%e0%b8%82%e0%b8%99%e0%b8%aa%e0%b9%88%e0%b8%87%e0%b8%9c%e0%b9%88%e0%b8%b2%e0%b8%99%e0%b9%81%e0%b8%94%e0%b8%99%e0%b8%a5%e0%b8%b2%e0%b8%a7%e0%b8%88%e0%b8%b5%e0%b8%99\/\">#\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e1c\u0e48\u0e32\u0e19\u0e41\u0e14\u0e19\u0e25\u0e32\u0e27\u0e08\u0e35\u0e19<\/a><a href=\"https:\/\/qualityaccessgloballogistics.com\/th\/tag\/%e0%b8%84%e0%b8%b2%e0%b8%a3%e0%b9%8c%e0%b9%82%e0%b8%81%e0%b9%89%e0%b8%88%e0%b8%b5%e0%b8%99\/\">#\u0e04\u0e32\u0e23\u0e4c\u0e42\u0e01\u0e49\u0e08\u0e35\u0e19<\/a><a href=\"https:\/\/qualityaccessgloballogistics.com\/th\/tag\/%e0%b8%84%e0%b8%b2%e0%b8%a3%e0%b9%8c%e0%b9%82%e0%b8%81%e0%b9%89%e0%b8%ad%e0%b8%b4%e0%b8%99%e0%b9%80%e0%b8%94%e0%b8%b5%e0%b8%a2\/\">#\u0e04\u0e32\u0e23\u0e4c\u0e42\u0e01\u0e49\u0e2d\u0e34\u0e19\u0e40\u0e14\u0e35\u0e22<\/a><a href=\"https:\/\/qualityaccessgloballogistics.com\/th\/tag\/%e0%b8%84%e0%b8%b2%e0%b8%a3%e0%b9%8c%e0%b9%82%e0%b8%81%e0%b9%89%e0%b8%ad%e0%b9%80%e0%b8%a1%e0%b8%a3%e0%b8%b4%e0%b8%81%e0%b8%b2\/\">#\u0e04\u0e32\u0e23\u0e4c\u0e42\u0e01\u0e49\u0e2d\u0e40\u0e21\u0e23\u0e34\u0e01\u0e32<\/a><a href=\"https:\/\/qualityaccessgloballogistics.com\/th\/tag\/%e0%b8%84%e0%b8%b2%e0%b8%a3%e0%b9%8c%e0%b9%82%e0%b8%81%e0%b9%89%e0%b9%80%e0%b8%a7%e0%b8%b5%e0%b8%a2%e0%b8%94%e0%b8%99%e0%b8%b2%e0%b8%a1\/\">#\u0e04\u0e32\u0e23\u0e4c\u0e42\u0e01\u0e49\u0e40\u0e27\u0e35\u0e22\u0e14\u0e19\u0e32\u0e21<\/a><a href=\"https:\/\/qualityaccessgloballogistics.com\/th\/tag\/%e0%b8%8a%e0%b8%b4%e0%b8%9b%e0%b8%9b%e0%b8%b4%e0%b9%89%e0%b8%87%e0%b8%88%e0%b8%b5%e0%b8%99\/\">#\u0e0a\u0e34\u0e1b\u0e1b\u0e34\u0e49\u0e07\u0e08\u0e35\u0e19<\/a><a href=\"https:\/\/qualityaccessgloballogistics.com\/th\/tag\/%e0%b8%8a%e0%b8%b4%e0%b8%9b%e0%b8%9b%e0%b8%b4%e0%b9%89%e0%b8%87%e0%b8%ad%e0%b8%b4%e0%b8%99%e0%b9%80%e0%b8%94%e0%b8%b5%e0%b8%a2\/\">#\u0e0a\u0e34\u0e1b\u0e1b\u0e34\u0e49\u0e07\u0e2d\u0e34\u0e19\u0e40\u0e14\u0e35\u0e22<\/a><a href=\"https:\/\/qualityaccessgloballogistics.com\/th\/tag\/%e0%b8%8a%e0%b8%b4%e0%b8%9b%e0%b8%9b%e0%b8%b4%e0%b9%89%e0%b8%87%e0%b8%ad%e0%b9%80%e0%b8%a1%e0%b8%a3%e0%b8%b4%e0%b8%81%e0%b8%b2\/\">#\u0e0a\u0e34\u0e1b\u0e1b\u0e34\u0e49\u0e07\u0e2d\u0e40\u0e21\u0e23\u0e34\u0e01\u0e32<\/a><a href=\"https:\/\/qualityaccessgloballogistics.com\/th\/tag\/%e0%b8%8a%e0%b8%b4%e0%b8%9b%e0%b8%9b%e0%b8%b4%e0%b9%89%e0%b8%87%e0%b9%80%e0%b8%a7%e0%b8%b5%e0%b8%a2%e0%b8%94%e0%b8%99%e0%b8%b2%e0%b8%a1\/\">#\u0e0a\u0e34\u0e1b\u0e1b\u0e34\u0e49\u0e07\u0e40\u0e27\u0e35\u0e22\u0e14\u0e19\u0e32\u0e21<\/a><a href=\"https:\/\/qualityaccessgloballogistics.com\/th\/tag\/%e0%b8%aa%e0%b9%88%e0%b8%87%e0%b8%82%e0%b8%ad%e0%b8%87%e0%b9%84%e0%b8%9b%e0%b8%88%e0%b8%b5%e0%b8%99\/\">#\u0e2a\u0e48\u0e07\u0e02\u0e2d\u0e07\u0e44\u0e1b\u0e08\u0e35\u0e19<\/a><a href=\"https:\/\/qualityaccessgloballogistics.com\/th\/tag\/%e0%b8%aa%e0%b9%88%e0%b8%87%e0%b8%82%e0%b8%ad%e0%b8%87%e0%b9%84%e0%b8%9b%e0%b8%ad%e0%b8%b4%e0%b8%99%e0%b9%80%e0%b8%94%e0%b8%b5%e0%b8%a2\/\">#\u0e2a\u0e48\u0e07\u0e02\u0e2d\u0e07\u0e44\u0e1b\u0e2d\u0e34\u0e19\u0e40\u0e14\u0e35\u0e22<\/a><a href=\"https:\/\/qualityaccessgloballogistics.com\/th\/tag\/%e0%b8%aa%e0%b9%88%e0%b8%87%e0%b8%82%e0%b8%ad%e0%b8%87%e0%b9%84%e0%b8%9b%e0%b8%ad%e0%b9%80%e0%b8%a1%e0%b8%a3%e0%b8%b4%e0%b8%81%e0%b8%b2\/\">#\u0e2a\u0e48\u0e07\u0e02\u0e2d\u0e07\u0e44\u0e1b\u0e2d\u0e40\u0e21\u0e23\u0e34\u0e01\u0e32<\/a><a href=\"https:\/\/qualityaccessgloballogistics.com\/th\/tag\/%e0%b8%aa%e0%b9%88%e0%b8%87%e0%b8%82%e0%b8%ad%e0%b8%87%e0%b9%84%e0%b8%9b%e0%b9%80%e0%b8%a7%e0%b8%b5%e0%b8%a2%e0%b8%94%e0%b8%99%e0%b8%b2%e0%b8%a1\/\">#\u0e2a\u0e48\u0e07\u0e02\u0e2d\u0e07\u0e44\u0e1b\u0e40\u0e27\u0e35\u0e22\u0e14\u0e19\u0e32\u0e21<\/a><a href=\"https:\/\/qualityaccessgloballogistics.com\/th\/tag\/%e0%b8%aa%e0%b9%88%e0%b8%87%e0%b8%aa%e0%b8%b4%e0%b8%99%e0%b8%84%e0%b9%89%e0%b8%b2%e0%b8%97%e0%b8%b2%e0%b8%87%e0%b9%80%e0%b8%84%e0%b8%a3%e0%b8%b7%e0%b9%88%e0%b8%ad%e0%b8%87%e0%b8%9a%e0%b8%b4%e0%b8%99\/\">#\u0e2a\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e32\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e34\u0e19 \u0e44\u0e1b\u0e40\u0e27\u0e35\u0e22\u0e14\u0e19\u0e32\u0e21<\/a><a href=\"https:\/\/qualityaccessgloballogistics.com\/th\/tag\/%e0%b8%aa%e0%b9%88%e0%b8%87%e0%b8%aa%e0%b8%b4%e0%b8%99%e0%b8%84%e0%b9%89%e0%b8%b2%e0%b8%97%e0%b8%b2%e0%b8%87%e0%b9%80%e0%b8%a3%e0%b8%b7%e0%b8%ad%e0%b9%84%e0%b8%9b%e0%b8%88%e0%b8%b5%e0%b8%99\/\">#\u0e2a\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e32\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e44\u0e1b\u0e08\u0e35\u0e19<\/a><a href=\"https:\/\/qualityaccessgloballogistics.com\/th\/tag\/%e0%b8%aa%e0%b9%88%e0%b8%87%e0%b8%aa%e0%b8%b4%e0%b8%99%e0%b8%84%e0%b9%89%e0%b8%b2%e0%b8%97%e0%b8%b2%e0%b8%87%e0%b9%80%e0%b8%a3%e0%b8%b7%e0%b8%ad%e0%b9%84%e0%b8%9b%e0%b8%ad%e0%b8%b4%e0%b8%99%e0%b9%80\/\">#\u0e2a\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e32\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e44\u0e1b\u0e2d\u0e34\u0e19\u0e40\u0e14\u0e35\u0e22<\/a><a href=\"https:\/\/qualityaccessgloballogistics.com\/th\/tag\/%e0%b8%aa%e0%b9%88%e0%b8%87%e0%b8%aa%e0%b8%b4%e0%b8%99%e0%b8%84%e0%b9%89%e0%b8%b2%e0%b8%97%e0%b8%b2%e0%b8%87%e0%b9%80%e0%b8%a3%e0%b8%b7%e0%b8%ad%e0%b9%84%e0%b8%9b%e0%b8%ad%e0%b9%80%e0%b8%a1%e0%b8%a3\/\">#\u0e2a\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e32\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e44\u0e1b\u0e2d\u0e40\u0e21\u0e23\u0e34\u0e01\u0e32<\/a><a href=\"https:\/\/qualityaccessgloballogistics.com\/th\/tag\/%e0%b8%aa%e0%b9%88%e0%b8%87%e0%b8%aa%e0%b8%b4%e0%b8%99%e0%b8%84%e0%b9%89%e0%b8%b2%e0%b8%97%e0%b8%b2%e0%b8%87%e0%b9%80%e0%b8%a3%e0%b8%b7%e0%b8%ad%e0%b9%84%e0%b8%9b%e0%b9%80%e0%b8%a7%e0%b8%b5%e0%b8%a2\/\">#\u0e2a\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e32\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e44\u0e1b\u0e40\u0e27\u0e35\u0e22\u0e14\u0e19\u0e32\u0e21<\/a><a href=\"https:\/\/qualityaccessgloballogistics.com\/th\/tag\/%e0%b8%aa%e0%b9%88%e0%b8%87%e0%b8%aa%e0%b8%b4%e0%b8%99%e0%b8%84%e0%b9%89%e0%b8%b2%e0%b9%84%e0%b8%9b%e0%b8%88%e0%b8%b5%e0%b8%99\/\">#\u0e2a\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e44\u0e1b\u0e08\u0e35\u0e19<\/a><a href=\"https:\/\/qualityaccessgloballogistics.com\/th\/tag\/%e0%b8%aa%e0%b9%88%e0%b8%87%e0%b8%aa%e0%b8%b4%e0%b8%99%e0%b8%84%e0%b9%89%e0%b8%b2%e0%b9%84%e0%b8%9b%e0%b8%ad%e0%b8%b4%e0%b8%99%e0%b9%80%e0%b8%94%e0%b8%b5%e0%b8%a2\/\">#\u0e2a\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e44\u0e1b\u0e2d\u0e34\u0e19\u0e40\u0e14\u0e35\u0e22<\/a><a href=\"https:\/\/qualityaccessgloballogistics.com\/th\/tag\/%e0%b8%aa%e0%b9%88%e0%b8%87%e0%b8%aa%e0%b8%b4%e0%b8%99%e0%b8%84%e0%b9%89%e0%b8%b2%e0%b9%84%e0%b8%9b%e0%b8%ad%e0%b9%80%e0%b8%a1%e0%b8%a3%e0%b8%b4%e0%b8%81%e0%b8%b2\/\">#\u0e2a\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e44\u0e1b\u0e2d\u0e40\u0e21\u0e23\u0e34\u0e01\u0e32<\/a><a href=\"https:\/\/qualityaccessgloballogistics.com\/th\/tag\/%e0%b8%aa%e0%b9%88%e0%b8%87%e0%b8%aa%e0%b8%b4%e0%b8%99%e0%b8%84%e0%b9%89%e0%b8%b2%e0%b9%84%e0%b8%9b%e0%b9%80%e0%b8%a7%e0%b8%b5%e0%b8%a2%e0%b8%94%e0%b8%99%e0%b8%b2%e0%b8%a1\/\">#\u0e2a\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e44\u0e1b\u0e40\u0e27\u0e35\u0e22\u0e14\u0e19\u0e32\u0e21<\/a>","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_kad_post_transparent":"default","_kad_post_title":"default","_kad_post_layout":"default","_kad_post_sidebar_id":"","_kad_post_content_style":"default","_kad_post_vertical_padding":"default","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"footnotes":""},"categories":[16],"tags":[34,25,29,33,21,23,27,31,19,24,28,32,20,18,22,26,30,17,36,37,38,35],"class_list":["post-2162","post","type-post","status-publish","format-standard","hentry","category-16","tag-34","tag-25","tag-29","tag-33","tag-21","tag-23","tag-27","tag-31","tag-19","tag-24","tag-28","tag-32","tag-20","tag-18","tag-22","tag-26","tag-30","tag-17","tag-36","tag-37","tag-38","tag-35"],"_links":{"self":[{"href":"https:\/\/qualityaccessgloballogistics.com\/th\/wp-json\/wp\/v2\/posts\/2162","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/qualityaccessgloballogistics.com\/th\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/qualityaccessgloballogistics.com\/th\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/qualityaccessgloballogistics.com\/th\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/qualityaccessgloballogistics.com\/th\/wp-json\/wp\/v2\/comments?post=2162"}],"version-history":[{"count":3,"href":"https:\/\/qualityaccessgloballogistics.com\/th\/wp-json\/wp\/v2\/posts\/2162\/revisions"}],"predecessor-version":[{"id":4698,"href":"https:\/\/qualityaccessgloballogistics.com\/th\/wp-json\/wp\/v2\/posts\/2162\/revisions\/4698"}],"wp:attachment":[{"href":"https:\/\/qualityaccessgloballogistics.com\/th\/wp-json\/wp\/v2\/media?parent=2162"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/qualityaccessgloballogistics.com\/th\/wp-json\/wp\/v2\/categories?post=2162"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/qualityaccessgloballogistics.com\/th\/wp-json\/wp\/v2\/tags?post=2162"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}